{"id":20896,"date":"2023-06-22T07:00:00","date_gmt":"2023-06-22T07:00:00","guid":{"rendered":"https:\/\/novelis2026.wpenginepowered.com\/news\/novelis-builds-first-onsite-solar-park-in-italy\/"},"modified":"2023-06-22T07:00:00","modified_gmt":"2023-06-22T07:00:00","slug":"novelis-builds-first-onsite-solar-park-in-italy","status":"publish","type":"news","link":"https:\/\/novelis.com\/de\/news\/novelis-builds-first-onsite-solar-park-in-italy\/","title":{"rendered":"Novelis baut ersten werkseigenen Solarpark in Italien"},"content":{"rendered":"<div id=\"armstrong-block-news-editor-block_de2dc2f1714ba1c01cf36c16ae752c58\" class=\"armstrong-block-news-editor\"  data-animate=\"fade-up\">\n    <p><span data-contrast=\"auto\">Novelis hat von den \u00f6rtlichen Beh\u00f6rden die endg\u00fcltige Genehmigung f\u00fcr den Bau seines ersten werkseigenen Solarparks am Produktionsstandort in Pieve, Italien, erhalten. Der Solarpark wird den CO2-Aussto\u00df um 1.450 Tonnen j\u00e4hrlich reduzieren, circa 12\u00a0Prozent des Stromverbrauchs des Werks decken und es Novelis erm\u00f6glichen, einen Gro\u00dfteil seiner kohlenstoffintensiven Energiequellen auf erneuerbare umzustellen.<\/span><\/p>\n<p><span data-ccp-props=\"{\"><span data-contrast=\"auto\" style=\"font-style: normal;font-weight: 400;font-size: 16px;\">Novelis hat sich zum Ziel gesetzt, seinen CO2-Fu\u00dfabdruck bis 2026 um 30\u00a0Prozent zu reduzieren und bis sp\u00e4testens 2050 Kohlenstoffneutralit\u00e4t zu erreichen. Mit diesem Projekt investiert das Unternehmen 2,4\u00a0Millionen US-Dollar in die Dekarbonisierung seiner Produktion in Pieve und treibt damit die Entwicklung von kohlenstoffarmen, nachhaltigen Aluminiuml\u00f6sungen f\u00fcr den europ\u00e4ischen Markt weiter voran.<\/span><span data-ccp-props=\"{\" style=\"font-style: normal;font-weight: 400;font-size: 16px;\">\u00a0<\/span>\u00a0<\/span><\/p>\n<\/div>","protected":false},"featured_media":19029,"template":"","news_category":[239],"location":[],"class_list":["post-20896","news","type-news","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Novelis baut ersten werkseigenen Solarpark in Italien<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/novelis.com\/de\/news\/novelis-builds-first-onsite-solar-park-in-italy\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Novelis baut ersten werkseigenen Solarpark in Italien\" \/>\n<meta property=\"og:url\" content=\"https:\/\/novelis.com\/de\/news\/novelis-builds-first-onsite-solar-park-in-italy\/\" \/>\n<meta property=\"og:site_name\" content=\"Novelis\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/novelis.com\\\/de\\\/news\\\/novelis-builds-first-onsite-solar-park-in-italy\\\/\",\"url\":\"https:\\\/\\\/novelis.com\\\/de\\\/news\\\/novelis-builds-first-onsite-solar-park-in-italy\\\/\",\"name\":\"Novelis baut ersten werkseigenen Solarpark in Italien\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/novelis.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/novelis.com\\\/de\\\/news\\\/novelis-builds-first-onsite-solar-park-in-italy\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/novelis.com\\\/de\\\/news\\\/novelis-builds-first-onsite-solar-park-in-italy\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/novelis.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Novelis-Solar-Park-in-Pieve_3D-Model-.webp\",\"datePublished\":\"2023-06-22T07:00:00+00:00\",\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/novelis.com\\\/de\\\/news\\\/novelis-builds-first-onsite-solar-park-in-italy\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/novelis.com\\\/de\\\/news\\\/novelis-builds-first-onsite-solar-park-in-italy\\\/#primaryimage\",\"url\":\"https:\\\/\\\/novelis.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Novelis-Solar-Park-in-Pieve_3D-Model-.webp\",\"contentUrl\":\"https:\\\/\\\/novelis.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Novelis-Solar-Park-in-Pieve_3D-Model-.webp\",\"width\":1920,\"height\":1080},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/novelis.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/novelis.com\\\/de\\\/\",\"name\":\"Novelis\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/novelis.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/novelis.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/novelis.com\\\/de\\\/#organization\",\"name\":\"Novelis\",\"url\":\"https:\\\/\\\/novelis.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/novelis.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/novelis.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Ventures_Logo.webp\",\"contentUrl\":\"https:\\\/\\\/novelis.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Ventures_Logo.webp\",\"width\":600,\"height\":220,\"caption\":\"Novelis\"},\"image\":{\"@id\":\"https:\\\/\\\/novelis.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Novelis baut ersten werkseigenen Solarpark in Italien","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/novelis.com\/de\/news\/novelis-builds-first-onsite-solar-park-in-italy\/","og_locale":"de_DE","og_type":"article","og_title":"Novelis baut ersten werkseigenen Solarpark in Italien","og_url":"https:\/\/novelis.com\/de\/news\/novelis-builds-first-onsite-solar-park-in-italy\/","og_site_name":"Novelis","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/novelis.com\/de\/news\/novelis-builds-first-onsite-solar-park-in-italy\/","url":"https:\/\/novelis.com\/de\/news\/novelis-builds-first-onsite-solar-park-in-italy\/","name":"Novelis baut ersten werkseigenen Solarpark in Italien","isPartOf":{"@id":"https:\/\/novelis.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/novelis.com\/de\/news\/novelis-builds-first-onsite-solar-park-in-italy\/#primaryimage"},"image":{"@id":"https:\/\/novelis.com\/de\/news\/novelis-builds-first-onsite-solar-park-in-italy\/#primaryimage"},"thumbnailUrl":"https:\/\/novelis.com\/wp-content\/uploads\/2026\/04\/Novelis-Solar-Park-in-Pieve_3D-Model-.webp","datePublished":"2023-06-22T07:00:00+00:00","inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/novelis.com\/de\/news\/novelis-builds-first-onsite-solar-park-in-italy\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/novelis.com\/de\/news\/novelis-builds-first-onsite-solar-park-in-italy\/#primaryimage","url":"https:\/\/novelis.com\/wp-content\/uploads\/2026\/04\/Novelis-Solar-Park-in-Pieve_3D-Model-.webp","contentUrl":"https:\/\/novelis.com\/wp-content\/uploads\/2026\/04\/Novelis-Solar-Park-in-Pieve_3D-Model-.webp","width":1920,"height":1080},{"@type":"WebSite","@id":"https:\/\/novelis.com\/de\/#website","url":"https:\/\/novelis.com\/de\/","name":"Novelis","description":"","publisher":{"@id":"https:\/\/novelis.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/novelis.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/novelis.com\/de\/#organization","name":"Novelis","url":"https:\/\/novelis.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/novelis.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/novelis.com\/wp-content\/uploads\/2026\/03\/Ventures_Logo.webp","contentUrl":"https:\/\/novelis.com\/wp-content\/uploads\/2026\/03\/Ventures_Logo.webp","width":600,"height":220,"caption":"Novelis"},"image":{"@id":"https:\/\/novelis.com\/de\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/novelis.com\/de\/wp-json\/wp\/v2\/news\/20896","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/novelis.com\/de\/wp-json\/wp\/v2\/news"}],"about":[{"href":"https:\/\/novelis.com\/de\/wp-json\/wp\/v2\/types\/news"}],"version-history":[{"count":0,"href":"https:\/\/novelis.com\/de\/wp-json\/wp\/v2\/news\/20896\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/novelis.com\/de\/wp-json\/wp\/v2\/media\/19029"}],"wp:attachment":[{"href":"https:\/\/novelis.com\/de\/wp-json\/wp\/v2\/media?parent=20896"}],"wp:term":[{"taxonomy":"news_category","embeddable":true,"href":"https:\/\/novelis.com\/de\/wp-json\/wp\/v2\/news_category?post=20896"},{"taxonomy":"location","embeddable":true,"href":"https:\/\/novelis.com\/de\/wp-json\/wp\/v2\/location?post=20896"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}